{"id":98,"count":93,"description":"","link":"https:\/\/www.tejidosanacordoba.es\/index.php\/categoria-producto\/tejidos\/ofertas\/","name":"OFERTAS","slug":"ofertas","taxonomy":"product_cat","parent":62,"meta":[],"menu_order":25,"_links":{"self":[{"href":"https:\/\/www.tejidosanacordoba.es\/index.php\/wp-json\/wp\/v2\/product_cat\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tejidosanacordoba.es\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.tejidosanacordoba.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.tejidosanacordoba.es\/index.php\/wp-json\/wp\/v2\/product_cat\/62"}],"wp:post_type":[{"href":"https:\/\/www.tejidosanacordoba.es\/index.php\/wp-json\/wp\/v2\/product?product_cat=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}